{"id":288,"date":"2019-07-05T11:22:27","date_gmt":"2019-07-05T09:22:27","guid":{"rendered":"http:\/\/pierrehenriet.fr\/?p=288"},"modified":"2021-01-21T11:25:09","modified_gmt":"2021-01-21T10:25:09","slug":"le-depute-a-la-rencontre-de-ses-concitoyens-dans-chacune-des-communes-du-sud-vendee","status":"publish","type":"post","link":"https:\/\/pierrehenriet.fr\/index.php\/2019\/07\/05\/le-depute-a-la-rencontre-de-ses-concitoyens-dans-chacune-des-communes-du-sud-vendee\/","title":{"rendered":"Le D\u00e9put\u00e9 \u00e0 la rencontre de ses concitoyens  dans chacune des communes du Sud-Vend\u00e9e"},"content":{"rendered":"\n<p>Pierre\nHenriet, D\u00e9put\u00e9 de la Vend\u00e9e, cl\u00f4t ce vendredi 5 juillet \u00e0 Maill\u00e9 la premi\u00e8re\ns\u00e9rie des permanences mobiles dans toutes les communes de la circonscription. Ce\nsont 89 r\u00e9unions qui ont \u00e9t\u00e9 programm\u00e9es les vendredis matin&nbsp;; la premi\u00e8re\ns\u2019est d\u00e9roul\u00e9e \u00e0 Vouvant&nbsp;le 15 f\u00e9vrier dernier. \u00c0 Maill\u00e9, ce vendredi 5\njuillet, c\u2019est la 49<sup>\u00e8me<\/sup> avant la suspension estivale.<\/p>\n\n\n\n<p><em>\u00ab&nbsp;Je fais un premier bilan et souhaite partager\nmes premi\u00e8res impressions&nbsp;:<\/em><\/p>\n\n\n\n<p><em>C\u2019est plus de 500 personnes que j\u2019ai rencontr\u00e9es sur\nl\u2019ensemble des communes concern\u00e9es. En plein c\u0153ur du Grand D\u00e9bat national lanc\u00e9\npar le Pr\u00e9sident de la R\u00e9publique, les premiers rendez-vous ont \u00e9t\u00e9 l\u2019occasion\nd\u2019exprimer en direct aupr\u00e8s de son d\u00e9put\u00e9, des revendications sur des sujets\ndiverses, de la limitation \u00e0 80km\/h aux difficult\u00e9s du quotidien.<\/em><\/p>\n\n\n\n<p><em>Ce fut aussi l\u2019occasion de pr\u00e9senter en priv\u00e9 des\nsituations personnelles, d\u2019\u00e9changer sur les r\u00e9formes en cours comme le syst\u00e8me\nde sant\u00e9 et principalement l\u2019acc\u00e8s aux soins ou \u00e0 venir comme celle des\nretraites ou d\u2019interroger sur l\u2019am\u00e9nagement de notre territoire.<\/em><\/p>\n\n\n\n<p><em>Tous les sujets qui pr\u00e9occupent nos concitoyens ont\n\u00e9t\u00e9 l\u2019objet de discussions internationales comme la vente d\u2019armes \u00e0 l\u2019Arabie\nSaoudite dans le cadre du conflit au Y\u00e9men ou de sujets plus locaux comme la\ntransition \u00e9cologique avec les projets \u00e9oliens.<\/em><\/p>\n\n\n\n<p><em>A la veille du renouvelement des conseils municipaux,\nje me r\u00e9jouis que la vie communale int\u00e9resse toujours&nbsp;: le transfert de\nnombreuses comp\u00e9tences communales \u00e0 l\u2019intercommunalit\u00e9 est souvent v\u00e9cu comme un\nd\u00e9classement de la Commune, voire une perte d\u2019identit\u00e9. Je peux confirmer que\nnos concitoyens sont exigeants sur l\u2019aspect \u00ab&nbsp;\u00e9conomie d\u2019\u00e9chelle&nbsp;\u00bb de\nces transferts. Je veux remercier les maires, les \u00e9lus municipaux et les\npersonnels communaux pour leur disponibilit\u00e9 et la qualit\u00e9 de leur accueil.<\/em><\/p>\n\n\n\n<p><em>Cette d\u00e9marche est appr\u00e9ci\u00e9e car chaque commune est\nconcern\u00e9e. Pour ceux n\u2019\u00e9tant pas disponibles le vendredi matin, j\u2019am\u00e9nage des\npermanences \u00e0 mon bureau situ\u00e9e \u00e0 Fontenay-le-Comte les samedis.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<p>Le rendez-vous\nest pris le 6 septembre \u00e0 Saint-Cyr-des-G\u00e2ts pour le d\u00e9but de la seconde s\u00e9rie\nqui se terminera le 20 d\u00e9cembre \u00e0 La Caill\u00e8re-Saint-Hilaire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pierre Henriet, D\u00e9put\u00e9 de la Vend\u00e9e, cl\u00f4t ce vendredi 5 juillet \u00e0 Maill\u00e9 la premi\u00e8re s\u00e9rie des permanences mobiles dans toutes les communes de la circonscription. Ce sont 89 r\u00e9unions qui ont \u00e9t\u00e9 programm\u00e9es les vendredis matin&nbsp;; la premi\u00e8re s\u2019est d\u00e9roul\u00e9e \u00e0 Vouvant&nbsp;le 15 f\u00e9vrier dernier. \u00c0 Maill\u00e9, ce vendredi 5 juillet, c\u2019est la 49\u00e8me [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communique-de-presse"],"uagb_featured_image_src":{"full":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49.png",1072,574,false],"thumbnail":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49-150x150.png",150,150,true],"medium":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49-300x161.png",300,161,true],"medium_large":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49-768x411.png",768,411,true],"large":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49-1024x548.png",1024,548,true],"post-slider-thumb-size":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49-330x190.png",330,190,true],"post-category-slider-size":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49.png",330,177,false],"1536x1536":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49.png",1072,574,false],"2048x2048":["https:\/\/pierrehenriet.fr\/wp-content\/uploads\/2021\/01\/Capture-d\u2019e\u0301cran-2021-01-21-a\u0300-11.24.49.png",1072,574,false]},"uagb_author_info":{"display_name":"Pierre Henriet","author_link":"https:\/\/pierrehenriet.fr\/index.php\/author\/admin8155\/"},"uagb_comment_info":0,"uagb_excerpt":"Pierre Henriet, D\u00e9put\u00e9 de la Vend\u00e9e, cl\u00f4t ce vendredi 5 juillet \u00e0 Maill\u00e9 la premi\u00e8re s\u00e9rie des permanences mobiles dans toutes les communes de la circonscription. Ce sont 89 r\u00e9unions qui ont \u00e9t\u00e9 programm\u00e9es les vendredis matin&nbsp;; la premi\u00e8re s\u2019est d\u00e9roul\u00e9e \u00e0 Vouvant&nbsp;le 15 f\u00e9vrier dernier. \u00c0 Maill\u00e9, ce vendredi 5 juillet, c\u2019est la 49\u00e8me\u2026","_links":{"self":[{"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/posts\/288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/comments?post=288"}],"version-history":[{"count":1,"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/posts\/288\/revisions"}],"predecessor-version":[{"id":290,"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/posts\/288\/revisions\/290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/media\/289"}],"wp:attachment":[{"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/media?parent=288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/categories?post=288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/tags?post=288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}