{"id":1,"name":"Pierre Henriet","url":"","description":"","link":"https:\/\/pierrehenriet.fr\/index.php\/author\/admin8155\/","slug":"admin8155","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a7c295164f27a76319826cef793c367be962680efe3a576ad9df2c2ee189f36e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a7c295164f27a76319826cef793c367be962680efe3a576ad9df2c2ee189f36e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a7c295164f27a76319826cef793c367be962680efe3a576ad9df2c2ee189f36e?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pierrehenriet.fr\/index.php\/wp-json\/wp\/v2\/users"}]}}